{"id":3547,"date":"2025-02-07T12:29:40","date_gmt":"2025-02-07T11:29:40","guid":{"rendered":"http:\/\/elmak.it\/?page_id=3547"},"modified":"2025-08-24T17:15:14","modified_gmt":"2025-08-24T15:15:14","slug":"lavora-con-noi","status":"publish","type":"page","link":"https:\/\/elmak.it\/it\/lavora-con-noi\/","title":{"rendered":"Lavora con noi"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3547\" class=\"elementor elementor-3547\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-152e815 e-flex e-con-boxed e-con e-parent\" data-id=\"152e815\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd77143 elementor-widget elementor-widget-heading\" data-id=\"cd77143\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><span class=\"text-gradient\">Lavora con noi<\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7ada95 elementor-widget elementor-widget-text-editor\" data-id=\"c7ada95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"162\" data-end=\"443\">Far parte di <b>Elmak <\/b>significa entrare in un contesto in continua evoluzione, dove l\u2019innovazione tecnologica rappresenta un valore fondamentale. Cerchiamo persone motivate, appassionate e curiose, capaci di contribuire alla crescita dell\u2019azienda con competenza e responsabilit\u00e0.<\/p><p data-start=\"445\" data-end=\"776\"><strong>Al momento non sono presenti posizioni aperte<\/strong>, tuttavia accogliamo con interesse <strong>candidature spontanee<\/strong> da parte di professionisti che desiderano entrare a far parte del nostro team. Tutte le candidature ricevute verranno attentamente valutate e, qualora in linea con le nostre esigenze e all&#8217;apertura di future posizioni lavorative, sar\u00e0 nostra cura ricontattare i candidati.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1379294 e-flex e-con-boxed e-con e-parent\" data-id=\"1379294\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f27c12a e-con-full card-box e-flex e-con e-child\" data-id=\"f27c12a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4b02ea elementor-widget elementor-widget-shortcode\" data-id=\"d4b02ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"elmak-form-wrapper\"><form id=\"elmak-candidature-form\" class=\"elmak-form candidature-form\" method=\"post\" autocomplete=\"off\" enctype=\"multipart\/form-data\" data-recaptcha=\"true\" data-recaptcha-action=\"candidature_form\"><input type=\"hidden\" id=\"elmak_nonce\" name=\"elmak_nonce\" value=\"1f38faf6fc\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/it\/wp-json\/wp\/v2\/pages\/3547\" \/><div style=\"position:absolute;left:-9999px;opacity:0;pointer-events:none;\" aria-hidden=\"true\"><input type=\"text\" name=\"wolf_site\" tabindex=\"-1\" autocomplete=\"off\"><input type=\"url\" name=\"wolf_link\" tabindex=\"-1\" autocomplete=\"off\"><input type=\"tel\" name=\"wolf_tel\" tabindex=\"-1\" autocomplete=\"off\"><input type=\"text\" name=\"wolf_org\" tabindex=\"-1\" autocomplete=\"off\"><\/div><input type=\"hidden\" name=\"recaptcha_token\" id=\"recaptcha_token\"><div class=\"row mb-0 mb-md-3\"><div class=\"col-md-6\"><div class=\"elmak-field-group \"><div class=\"input-group\"><span class=\"input-group-text\"><i class=\"elmak elmak-user\"><\/i><\/span><input type=\"text\" name=\"candidatura_nome\" id=\"candidatura_nome\" class=\"form-control \" value=\"\" required><div class=\"floating-label\" data-field=\"candidatura_nome\"><label for=\"candidatura_nome\">Nome <span class=\"required\">*<\/span><\/label><\/div><\/div><\/div><\/div><div class=\"col-md-6\"><div class=\"elmak-field-group \"><div class=\"input-group\"><span class=\"input-group-text\"><i class=\"elmak elmak-user\"><\/i><\/span><input type=\"text\" name=\"candidatura_cognome\" id=\"candidatura_cognome\" class=\"form-control \" value=\"\" required><div class=\"floating-label\" data-field=\"candidatura_cognome\"><label for=\"candidatura_cognome\">Cognome <span class=\"required\">*<\/span><\/label><\/div><\/div><\/div><\/div><\/div><div class=\"row mb-0 mb-md-3\"><div class=\"col-md-6\"><div class=\"elmak-field-group \"><div class=\"input-group\"><span class=\"input-group-text\"><i class=\"elmak elmak-mail\"><\/i><\/span><input type=\"email\" name=\"candidatura_email\" id=\"candidatura_email\" class=\"form-control \" value=\"\" required><div class=\"floating-label\" data-field=\"candidatura_email\"><label for=\"candidatura_email\">Email <span class=\"required\">*<\/span><\/label><\/div><\/div><\/div><\/div><div class=\"col-md-6\"><div class=\"elmak-field-group \"><div class=\"input-group\"><span class=\"input-group-text\"><i class=\"elmak elmak-phone\"><\/i><\/span><input type=\"tel\" name=\"candidatura_telefono\" id=\"candidatura_telefono\" class=\"form-control \" value=\"\" required><div class=\"floating-label\" data-field=\"candidatura_telefono\"><label for=\"candidatura_telefono\">Telefono <span class=\"required\">*<\/span><\/label><\/div><\/div><\/div><\/div><\/div><div class=\"row mb-0 mb-md-3\"><div class=\"col-md-6\"><div class=\"elmak-field-group \"><div class=\"input-group\"><span class=\"input-group-text\"><i class=\"elmak elmak-briefcase\"><\/i><\/span><input type=\"text\" name=\"candidatura_ruolo\" id=\"candidatura_ruolo\" class=\"form-control \" value=\"\" required><div class=\"floating-label\" data-field=\"candidatura_ruolo\"><label for=\"candidatura_ruolo\">Posizione di interesse <span class=\"required\">*<\/span><\/label><\/div><\/div><\/div><\/div><div class=\"col-md-6\"><div class=\"elmak-field-group \"><div class=\"input-group\"><span class=\"input-group-text\"><i class=\"elmak elmak-map-pin\"><\/i><\/span><input type=\"text\" name=\"candidatura_comune\" id=\"candidatura_comune\" class=\"form-control \" value=\"\" required><div class=\"floating-label\" data-field=\"candidatura_comune\"><label for=\"candidatura_comune\">Citt\u00e0 di residenza <span class=\"required\">*<\/span><\/label><\/div><\/div><\/div><\/div><\/div><div class=\"row mb-0 mb-md-3\"><div class=\"col-12\"><div class=\"elmak-field-group \"><div class=\"input-group textarea\"><span class=\"input-group-text\"><i class=\"elmak elmak-message-square\"><\/i><\/span><textarea name=\"candidatura_messaggio\" id=\"candidatura_messaggio\" class=\"form-control \" rows=\"5\" required><\/textarea><div class=\"floating-label\" data-field=\"candidatura_messaggio\"><label for=\"candidatura_messaggio\">Lettera di presentazione <span class=\"required\">*<\/span><\/label><\/div><\/div><\/div><\/div><\/div><div class=\"row mb-0 mb-md-3\"><div class=\"col-12\"><div class=\"elmak-field-group \"><div class=\"select-label\" data-field=\"candidatura_cv\"><label for=\"candidatura_cv\">Carica il tuo CV <span class=\"required\">*<\/span><\/label><\/div><div class=\"elmak-file-upload\"><input type=\"file\" name=\"candidatura_cv\" id=\"candidatura_cv\" class=\"form-control \" accept=\".pdf,.doc,.docx\" required><\/div><\/div><\/div><\/div><div class=\"row mb-0 mb-md-3\"><div class=\"col-12\"><div class=\"elmak-field-group \"><div class=\"form-check elmak-checkbox\"><input type=\"checkbox\" name=\"contact_privacy\" id=\"contact_privacy_1\" class=\"form-check-input \" value=\"1\"  required><label class=\"form-check-label\" for=\"contact_privacy_1\">Accetto le <a href=\"https:\/\/www.iubenda.com\/privacy-policy\/86651300\" target=\"_blank\">Informativa sulla privacy<\/a> e autorizzo il trattamento dei miei dati personali <span class=\"required\">*<\/span><\/label><\/div><\/div><\/div><\/div><div class=\"elmak-recaptcha-info\">Questo sito \u00e8 protetto da reCAPTCHA e si applicano le <a href=\"https:\/\/policies.google.com\/privacy\" target=\"_blank\" rel=\"noopener\">Informativa sulla privacy<\/a> e <a href=\"https:\/\/policies.google.com\/terms\" target=\"_blank\" rel=\"noopener\">Termini di servizio<\/a> di Google.<\/div><div class=\"elmak-form-submit\"><button type=\"submit\" class=\"btn btn-primary btn-primary btn-lg\">Invia la domanda<\/button><\/div><\/form><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Lavora con noi Far parte di Elmak significa entrare in un contesto in continua evoluzione, dove l\u2019innovazione tecnologica rappresenta un valore fondamentale. Cerchiamo persone motivate, appassionate e curiose, capaci di contribuire alla crescita dell\u2019azienda con competenza e responsabilit\u00e0. Al momento non sono presenti posizioni aperte, tuttavia accogliamo con interesse candidature spontanee da parte di professionisti [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3547","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lavora con noi - Elmak<\/title>\n<meta name=\"description\" content=\"Invia la tua candidatura spontanea se vuoi entrare in Elmak e lavorare in un ambiente in evoluzione, dove l\u2019innovazione tecnologica \u00e8 fondamentale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elmak.it\/it\/lavora-con-noi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lavora con noi\" \/>\n<meta property=\"og:description\" content=\"Invia la tua candidatura spontanea se vuoi entrare in Elmak e lavorare in un ambiente in evoluzione, dove l\u2019innovazione tecnologica \u00e8 fondamentale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elmak.it\/it\/lavora-con-noi\/\" \/>\n<meta property=\"og:site_name\" content=\"Elmak\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-24T15:15:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elmak.it\/wp-content\/uploads\/2025\/08\/fallback-seo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elmak.it\\\/it\\\/lavora-con-noi\\\/\",\"url\":\"https:\\\/\\\/elmak.it\\\/it\\\/lavora-con-noi\\\/\",\"name\":\"Lavora con noi - Elmak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elmak.it\\\/it\\\/#website\"},\"datePublished\":\"2025-02-07T11:29:40+00:00\",\"dateModified\":\"2025-08-24T15:15:14+00:00\",\"description\":\"Invia la tua candidatura spontanea se vuoi entrare in Elmak e lavorare in un ambiente in evoluzione, dove l\u2019innovazione tecnologica \u00e8 fondamentale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elmak.it\\\/it\\\/lavora-con-noi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elmak.it\\\/it\\\/lavora-con-noi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elmak.it\\\/it\\\/lavora-con-noi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elmak.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lavora con noi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elmak.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/elmak.it\\\/it\\\/\",\"name\":\"Elmak\",\"description\":\"PC e monitor per l&#039;automazione industriale\",\"publisher\":{\"@id\":\"https:\\\/\\\/elmak.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elmak.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elmak.it\\\/it\\\/#organization\",\"name\":\"Elmak\",\"url\":\"https:\\\/\\\/elmak.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/elmak.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/elmak.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Elmak-dark-horizontal-RGB-WEB.png\",\"contentUrl\":\"http:\\\/\\\/elmak.it\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Elmak-dark-horizontal-RGB-WEB.png\",\"width\":1500,\"height\":600,\"caption\":\"Elmak\"},\"image\":{\"@id\":\"https:\\\/\\\/elmak.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"description\":\"Elmak S.r.l. \u2014 Hardware per l\u2019automazione industriale. Progettiamo, personalizziamo e distribuiamo Panel PC, monitor touchscreen, PC box e sistemi rugged altamente affidabili. Con oltre dieci anni di esperienza, offriamo assistenza post-vendita dedicata, garanzia e consulenza tecnica per soluzioni su misura, pensate per aumentare la produttivit\u00e0 e ridurre i costi operativi.\",\"email\":\"info@elmak.it\",\"telephone\":\"+39 0522 1753130\",\"legalName\":\"Elmak\",\"vatID\":\"02568750356\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lavora con noi - Elmak","description":"Invia la tua candidatura spontanea se vuoi entrare in Elmak e lavorare in un ambiente in evoluzione, dove l\u2019innovazione tecnologica \u00e8 fondamentale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elmak.it\/it\/lavora-con-noi\/","og_locale":"it_IT","og_type":"article","og_title":"Lavora con noi","og_description":"Invia la tua candidatura spontanea se vuoi entrare in Elmak e lavorare in un ambiente in evoluzione, dove l\u2019innovazione tecnologica \u00e8 fondamentale.","og_url":"https:\/\/elmak.it\/it\/lavora-con-noi\/","og_site_name":"Elmak","article_modified_time":"2025-08-24T15:15:14+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/elmak.it\/wp-content\/uploads\/2025\/08\/fallback-seo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elmak.it\/it\/lavora-con-noi\/","url":"https:\/\/elmak.it\/it\/lavora-con-noi\/","name":"Lavora con noi - Elmak","isPartOf":{"@id":"https:\/\/elmak.it\/it\/#website"},"datePublished":"2025-02-07T11:29:40+00:00","dateModified":"2025-08-24T15:15:14+00:00","description":"Invia la tua candidatura spontanea se vuoi entrare in Elmak e lavorare in un ambiente in evoluzione, dove l\u2019innovazione tecnologica \u00e8 fondamentale.","breadcrumb":{"@id":"https:\/\/elmak.it\/it\/lavora-con-noi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elmak.it\/it\/lavora-con-noi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elmak.it\/it\/lavora-con-noi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elmak.it\/it\/"},{"@type":"ListItem","position":2,"name":"Lavora con noi"}]},{"@type":"WebSite","@id":"https:\/\/elmak.it\/it\/#website","url":"https:\/\/elmak.it\/it\/","name":"Elmak","description":"PC e monitor per l&#039;automazione industriale","publisher":{"@id":"https:\/\/elmak.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elmak.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/elmak.it\/it\/#organization","name":"Elmak","url":"https:\/\/elmak.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/elmak.it\/it\/#\/schema\/logo\/image\/","url":"http:\/\/elmak.it\/wp-content\/uploads\/2025\/08\/Elmak-dark-horizontal-RGB-WEB.png","contentUrl":"http:\/\/elmak.it\/wp-content\/uploads\/2025\/08\/Elmak-dark-horizontal-RGB-WEB.png","width":1500,"height":600,"caption":"Elmak"},"image":{"@id":"https:\/\/elmak.it\/it\/#\/schema\/logo\/image\/"},"description":"Elmak S.r.l. \u2014 Hardware per l\u2019automazione industriale. Progettiamo, personalizziamo e distribuiamo Panel PC, monitor touchscreen, PC box e sistemi rugged altamente affidabili. Con oltre dieci anni di esperienza, offriamo assistenza post-vendita dedicata, garanzia e consulenza tecnica per soluzioni su misura, pensate per aumentare la produttivit\u00e0 e ridurre i costi operativi.","email":"info@elmak.it","telephone":"+39 0522 1753130","legalName":"Elmak","vatID":"02568750356"}]}},"_links":{"self":[{"href":"https:\/\/elmak.it\/it\/wp-json\/wp\/v2\/pages\/3547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elmak.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elmak.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elmak.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elmak.it\/it\/wp-json\/wp\/v2\/comments?post=3547"}],"version-history":[{"count":0,"href":"https:\/\/elmak.it\/it\/wp-json\/wp\/v2\/pages\/3547\/revisions"}],"wp:attachment":[{"href":"https:\/\/elmak.it\/it\/wp-json\/wp\/v2\/media?parent=3547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}